{"id":13883,"date":"2021-10-03T10:00:39","date_gmt":"2021-10-03T08:00:39","guid":{"rendered":"https:\/\/solkes.com\/?p=13883"},"modified":"2021-03-12T17:33:21","modified_gmt":"2021-03-12T15:33:21","slug":"leipaja-sumergiendonos-en-el-pasado","status":"publish","type":"post","link":"https:\/\/solkes.com\/de\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/","title":{"rendered":"Leipaja: sumergi\u00e9ndonos en el pasado"},"content":{"rendered":"<p><span style=\"color: #138a8d;\">D<\/span>ebo decirlo, todos hemos o\u00eddo hablar sobre el turismo extremo. Es b\u00e1sicamente, estar en una situaci\u00f3n limite, ya sea saltar de un puente, de una roca, nadar con tiburones, etc. Ahora bien, esa era la concepci\u00f3n t\u00edpica de turismo extremo y el nuevo concepto es bastante diferente.<\/p>\n<h3><span style=\"color: #138a8d;\"><strong>Buscando algo diferente<\/strong><\/span><\/h3>\n<p>Ejemplo perfecto es el de quedarse y hacer parte de una prisi\u00f3n en una antigua rep\u00fablica sovi\u00e9tica. La idea de este plan es quedarse a dormir en la c\u00e1rcel y ser cuidado como un prisionero real.<\/p>\n<figure id=\"attachment_13892\" aria-describedby=\"caption-attachment-13892\" style=\"width: 943px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-solkes_horizontal wp-image-13892\" src=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_04.jpg\" alt=\"\" width=\"943\" height=\"601\" srcset=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_04.jpg 943w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_04-300x191.jpg 300w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_04-768x489.jpg 768w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_04-320x204.jpg 320w\" sizes=\"(max-width: 943px) 100vw, 943px\" \/><figcaption id=\"caption-attachment-13892\" class=\"wp-caption-text\">Betty Boop \u00a9 Solkes<\/figcaption><\/figure>\n<p>Esto es una estad\u00eda extrema en toda regla y la verdad es que no es un juego de ni\u00f1os. Este es el ambiente que ofrece la prisi\u00f3n Karosta en Letonia. Muy a las afueras de la realidad actual, lejos de la luces citadinas, las organizaciones de derechos humanos uno puede tener la oportunidad, as\u00ed sea por unas horas, de ser un recluso.<\/p>\n<p>Eso si ac\u00e1, no es posible viajar con menores de edad, unicamente se permiten personas que firmen una declaraci\u00f3n en las que se acceptan las condiciones extremas. Pero, si lo suyo no es tan hard core pues es posible pagar por estar durante una joranda entera tras las rejas.<\/p>\n<h3><strong><span style=\"color: #138a8d;\">La historia<\/span><\/strong><\/h3>\n<p>El Hotel c\u00e1rcel se encuentra en la localidad costera del b\u00e1ltico llamada Liepaja y est\u00e1 en un fuerte que custodiaba este estrat\u00e9gico puerto del B\u00e1ltico. Funcion\u00f3 desde la \u00e9poca zarista hasta que en 1997 se propuso reciclarla y darle un prop\u00f3sito tur\u00edstico, advirti\u00e9ndole a los usuarios que el edificio fue concebido para &#8220;romper la vida de la gente y su libertad&#8221;.<\/p>\n<figure id=\"attachment_13894\" aria-describedby=\"caption-attachment-13894\" style=\"width: 374px\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\"size-solkes_horizontal wp-image-13894\" src=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_01-374x601.jpg\" alt=\"\" width=\"374\" height=\"601\" srcset=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_01-374x601.jpg 374w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_01-187x300.jpg 187w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_01.jpg 620w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_01-299x480.jpg 299w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/><figcaption id=\"caption-attachment-13894\" class=\"wp-caption-text\">Betty Boop \u00a9 Solkes<\/figcaption><\/figure>\n<p>Durante los a\u00f1os de funcionamiento, la vida en este c\u00e1rcel no fue ning\u00fan para\u00edso. Fueron muchas las personas que pagaron condenas, sufrieron y murieron entre sus paredes. Y, todo esto psoiblemente en regimenes distintos: sovi\u00e9tico, el nazi o el let\u00f3n. Por ejemplo, en el caso nazi, durante la II Guerra Mundial, Hitler enviaba all\u00ed a las personas condenadas a muerte por desertar y Karostas era su destino final y el lugar elegido para ejecutarlos.<\/p>\n<p>Entre las \u201ccomodidades\u201d que ofrece el hotel-carcel se encuentran sus camastros de hierro, comida de c\u00e1rcel, s\u00f3lo agua fr\u00eda para ba\u00f1arse, interrogatorios, caminatas nocturnas, gritos a cualquier hora, flexiones, la limpieza de los ba\u00f1os y castigos en caso de no cumplir con las \u00f3rdenes.<\/p>\n<p>Hay que decirlo: este es un espect\u00e1culo de realidad hist\u00f3rica. Esta obviamente, basado en situaciones reales, situaciones que seguramente vivieron entre esos corredores y que no siempre tuvieron un final feliz. El prop\u00f3sito y la esencia del show es dar a cada participante la oportunidad de vivir el papel de un preso y aprender acerca de los hechos m\u00e1s interesantes e impactantes de la historia de la prisi\u00f3n.<\/p>\n<h3><span style=\"color: #138a8d;\"><strong>Es un hotel no un museo<\/strong><\/span><\/h3>\n<p>Para los que aun no lo han entendido, esto es un hotel no un museo. Aqu\u00ed ver\u00e1s una prisi\u00f3n que no ha experimentado un cambio casi desde los tiempos zaristas, usted aprender\u00e1 acerca de c\u00f3mo sobreviv\u00edan los detenidos, como se siente un prisionero en su celda.<\/p>\n<figure id=\"attachment_13896\" aria-describedby=\"caption-attachment-13896\" style=\"width: 374px\" class=\"wp-caption alignleft\"><img decoding=\"async\" class=\"size-solkes_horizontal wp-image-13896\" src=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_02-374x601.jpg\" alt=\"\" width=\"374\" height=\"601\" srcset=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_02-374x601.jpg 374w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_02-187x300.jpg 187w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_02.jpg 620w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_02-299x480.jpg 299w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/><figcaption id=\"caption-attachment-13896\" class=\"wp-caption-text\">Betty Boop \u00a9 Solkes<\/figcaption><\/figure>\n<p>Una de las opciones es la de descansar en la cantina de la c\u00e1rcel y comprar recuerdos aut\u00e9nticos del puerto naval de la era sovi\u00e9tica. Como parte del tour, usted tendr\u00e1 la oportunidad de ver un documental de 16 minutos hablando acerca de la construcci\u00f3n y de la historia del Puerto Naval. Tours empiezan de las diez a las cinco horas.<\/p>\n<p><span style=\"font-size: 16px; text-align: center;\">Los cuartos son celdas que han mantenido como en la segunda guerra mundial. Hay camastros de hierro, por supuesto sin calefacci\u00f3n ni agua caliente, y los manjares que te ofrecen para sentirte un conspirador del Stalinismo son sus potajes y potingues. El precio para dormir bajo estas condiciones es de 11,50\u20ac.<\/span><\/p>\n<p>Pero, como hay gente que siempre queda con ganas de m\u00e1s, existe la opci\u00f3n detener una noche m\u00e1s intensa: EXTREME NIGHT. Eso si, para vivirla es necesario firmar un acuerdo en que te sometes a las reglas del juego que consisten en que a partir de cruzar la puerta te conviertes en un PRISIONERO.<\/p>\n<p>Como tal, seras suceptible a aceptar las \u00f3rdenes &#8220;abusivas&#8221; que te den. Su desobediencia puede estar penada con ejercicios f\u00edsicos duros o limpieza de retretes, incluso con la expulsi\u00f3n del Centro. Este juego cuesta 18\u20ac.<\/p>\n<h3><strong><span style=\"color: #138a8d;\">La conclusi\u00f3n<\/span><\/strong><\/h3>\n<p>En todo caso, estar en este hotel &#8211; c\u00e1rcel ofrece una experiencia \u00fanica. Quien se hubiera imaginado que Leipaja ofrecer\u00eda al mundo esta experiencia extrema. Bueno, como dicen es Espa\u00f1a: para gustos los colores.<\/p>\n<figure id=\"attachment_13890\" aria-describedby=\"caption-attachment-13890\" style=\"width: 943px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-solkes_horizontal wp-image-13890\" src=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg\" alt=\"\" width=\"943\" height=\"601\" srcset=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg 943w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03-300x191.jpg 300w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03-768x489.jpg 768w, https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03-320x204.jpg 320w\" sizes=\"(max-width: 943px) 100vw, 943px\" \/><figcaption id=\"caption-attachment-13890\" class=\"wp-caption-text\">Betty Boop \u00a9 Solkes<\/figcaption><\/figure>\n<p>Por eso se que hay personas que este plan, el de estar en un hotel c\u00e1rcel, les encantara. Al final de la gira, usted ser\u00e1 capaz de convertirse en trajes militares de diferentes edades y sacar unas fotos. A mi me da estr\u00e9s, simplemente es: demasiado estr\u00e9s para unas vacaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debo decirlo, todos hemos o\u00eddo hablar sobre el turismo extremo. Es b\u00e1sicamente, estar en una situaci\u00f3n limite, ya sea saltar de un puente, de una roca, nadar con tiburones, etc. Ahora bien, esa era la concepci\u00f3n t\u00edpica de turismo extremo y el nuevo concepto es bastante diferente. Buscando algo diferente Ejemplo perfecto es el de [&hellip;]<\/p>\n","protected":false},"author":91,"featured_media":13890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[18],"tags":[],"class_list":["post-13883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-x-el-mundo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leipaja: sumergi\u00e9ndonos en el pasado - Solkes Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leipaja: sumergi\u00e9ndonos en el pasado - Solkes Magazine\" \/>\n<meta property=\"og:description\" content=\"Debo decirlo, todos hemos o\u00eddo hablar sobre el turismo extremo. Es b\u00e1sicamente, estar en una situaci\u00f3n limite, ya sea saltar de un puente, de una roca, nadar con tiburones, etc. Ahora bien, esa era la concepci\u00f3n t\u00edpica de turismo extremo y el nuevo concepto es bastante diferente. Buscando algo diferente Ejemplo perfecto es el de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/\" \/>\n<meta property=\"og:site_name\" content=\"Solkes Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/solkesmagazinee\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-03T08:00:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"943\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nessa Twix\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nessa Twix\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/\"},\"author\":{\"name\":\"Nessa Twix\",\"@id\":\"https:\\\/\\\/solkes.com\\\/#\\\/schema\\\/person\\\/b13fbbba3b3146326f81dbeb3fa5d147\"},\"headline\":\"Leipaja: sumergi\u00e9ndonos en el pasado\",\"datePublished\":\"2021-10-03T08:00:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/\"},\"wordCount\":884,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solkes.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/leipaja-2110_03.jpg\",\"articleSection\":[\"X El Mundo\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/\",\"url\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/\",\"name\":\"Leipaja: sumergi\u00e9ndonos en el pasado - Solkes Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solkes.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/leipaja-2110_03.jpg\",\"datePublished\":\"2021-10-03T08:00:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solkes.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/leipaja-2110_03.jpg\",\"contentUrl\":\"https:\\\/\\\/solkes.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/leipaja-2110_03.jpg\",\"width\":943,\"height\":601,\"caption\":\"Betty Boop \u00a9 Solkes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solkes.com\\\/x-el-mundo\\\/2021\\\/10\\\/leipaja-sumergiendonos-en-el-pasado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/solkes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leipaja: sumergi\u00e9ndonos en el pasado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solkes.com\\\/#website\",\"url\":\"https:\\\/\\\/solkes.com\\\/\",\"name\":\"Solkes Magazine\",\"description\":\"solkes.com\",\"publisher\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solkes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solkes.com\\\/#organization\",\"name\":\"Solkes Magazine\",\"url\":\"https:\\\/\\\/solkes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/solkes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solkes.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-SOLKES-820px-x-312px.png\",\"contentUrl\":\"https:\\\/\\\/solkes.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/logo-SOLKES-820px-x-312px.png\",\"width\":411,\"height\":303,\"caption\":\"Solkes Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/solkes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/solkesmagazinee\\\/\",\"https:\\\/\\\/instagram.com\\\/solkesmagazine\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solkes.com\\\/#\\\/schema\\\/person\\\/b13fbbba3b3146326f81dbeb3fa5d147\",\"name\":\"Nessa Twix\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8cb33f784abaa7bcc5b4058902fad344ca93ae216fce5473bc825f086cc5a567?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8cb33f784abaa7bcc5b4058902fad344ca93ae216fce5473bc825f086cc5a567?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8cb33f784abaa7bcc5b4058902fad344ca93ae216fce5473bc825f086cc5a567?s=96&d=identicon&r=g\",\"caption\":\"Nessa Twix\"},\"description\":\"Nessa Twix es una amante de la fotograf\u00eda, del arte, del buen cine y la buena comida. Se considera ciudadana del mundo. Para ella las fronteras no existen. Es un poco t\u00edmida pero deja que sus emociones cobren forma entre la tinta y los colores. ******* Nessa is passionate about photography, art, good movies, and good food. She considers herself to be a World Citizen. For her borders are unexistent. She is shy but her feelings and emotions come out with ink and colors.\",\"url\":\"https:\\\/\\\/solkes.com\\\/de\\\/author\\\/nessa-twix\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leipaja: sumergi\u00e9ndonos en el pasado - Solkes Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/","og_locale":"de_DE","og_type":"article","og_title":"Leipaja: sumergi\u00e9ndonos en el pasado - Solkes Magazine","og_description":"Debo decirlo, todos hemos o\u00eddo hablar sobre el turismo extremo. Es b\u00e1sicamente, estar en una situaci\u00f3n limite, ya sea saltar de un puente, de una roca, nadar con tiburones, etc. Ahora bien, esa era la concepci\u00f3n t\u00edpica de turismo extremo y el nuevo concepto es bastante diferente. Buscando algo diferente Ejemplo perfecto es el de [&hellip;]","og_url":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/","og_site_name":"Solkes Magazine","article_publisher":"https:\/\/www.facebook.com\/solkesmagazinee\/","article_published_time":"2021-10-03T08:00:39+00:00","og_image":[{"width":943,"height":601,"url":"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg","type":"image\/jpeg"}],"author":"Nessa Twix","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Nessa Twix","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#article","isPartOf":{"@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/"},"author":{"name":"Nessa Twix","@id":"https:\/\/solkes.com\/#\/schema\/person\/b13fbbba3b3146326f81dbeb3fa5d147"},"headline":"Leipaja: sumergi\u00e9ndonos en el pasado","datePublished":"2021-10-03T08:00:39+00:00","mainEntityOfPage":{"@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/"},"wordCount":884,"commentCount":0,"publisher":{"@id":"https:\/\/solkes.com\/#organization"},"image":{"@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#primaryimage"},"thumbnailUrl":"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg","articleSection":["X El Mundo"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/","url":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/","name":"Leipaja: sumergi\u00e9ndonos en el pasado - Solkes Magazine","isPartOf":{"@id":"https:\/\/solkes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#primaryimage"},"image":{"@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#primaryimage"},"thumbnailUrl":"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg","datePublished":"2021-10-03T08:00:39+00:00","breadcrumb":{"@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#primaryimage","url":"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg","contentUrl":"https:\/\/solkes.com\/wp-content\/uploads\/2021\/10\/leipaja-2110_03.jpg","width":943,"height":601,"caption":"Betty Boop \u00a9 Solkes"},{"@type":"BreadcrumbList","@id":"https:\/\/solkes.com\/x-el-mundo\/2021\/10\/leipaja-sumergiendonos-en-el-pasado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/solkes.com\/"},{"@type":"ListItem","position":2,"name":"Leipaja: sumergi\u00e9ndonos en el pasado"}]},{"@type":"WebSite","@id":"https:\/\/solkes.com\/#website","url":"https:\/\/solkes.com\/","name":"Solkes Magazine","description":"solkes.com","publisher":{"@id":"https:\/\/solkes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solkes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/solkes.com\/#organization","name":"Solkes Magazine","url":"https:\/\/solkes.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/solkes.com\/#\/schema\/logo\/image\/","url":"https:\/\/solkes.com\/wp-content\/uploads\/2024\/09\/logo-SOLKES-820px-x-312px.png","contentUrl":"https:\/\/solkes.com\/wp-content\/uploads\/2024\/09\/logo-SOLKES-820px-x-312px.png","width":411,"height":303,"caption":"Solkes Magazine"},"image":{"@id":"https:\/\/solkes.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/solkesmagazinee\/","https:\/\/instagram.com\/solkesmagazine\/"]},{"@type":"Person","@id":"https:\/\/solkes.com\/#\/schema\/person\/b13fbbba3b3146326f81dbeb3fa5d147","name":"Nessa Twix","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/8cb33f784abaa7bcc5b4058902fad344ca93ae216fce5473bc825f086cc5a567?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8cb33f784abaa7bcc5b4058902fad344ca93ae216fce5473bc825f086cc5a567?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8cb33f784abaa7bcc5b4058902fad344ca93ae216fce5473bc825f086cc5a567?s=96&d=identicon&r=g","caption":"Nessa Twix"},"description":"Nessa Twix es una amante de la fotograf\u00eda, del arte, del buen cine y la buena comida. Se considera ciudadana del mundo. Para ella las fronteras no existen. Es un poco t\u00edmida pero deja que sus emociones cobren forma entre la tinta y los colores. ******* Nessa is passionate about photography, art, good movies, and good food. She considers herself to be a World Citizen. For her borders are unexistent. She is shy but her feelings and emotions come out with ink and colors.","url":"https:\/\/solkes.com\/de\/author\/nessa-twix\/"}]}},"_links":{"self":[{"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/posts\/13883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/comments?post=13883"}],"version-history":[{"count":4,"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/posts\/13883\/revisions"}],"predecessor-version":[{"id":13887,"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/posts\/13883\/revisions\/13887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/media\/13890"}],"wp:attachment":[{"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/media?parent=13883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/categories?post=13883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solkes.com\/de\/wp-json\/wp\/v2\/tags?post=13883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}